{"id":3169,"date":"2023-09-07T13:31:47","date_gmt":"2023-09-07T10:31:47","guid":{"rendered":"https:\/\/www.laplandrestaurant.fi\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314\/"},"modified":"2023-09-07T13:31:47","modified_gmt":"2023-09-07T10:31:47","slug":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-6","status":"inherit","type":"attachment","link":"https:\/\/laplandrestaurant.fi\/fi\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-6\/","title":{"rendered":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3169","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi\" \/>\n<meta property=\"og:url\" content=\"\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Lapland Restaurant Kotahovi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\\\/userassets\\\/uploads\\\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\",\"url\":\"https:\\\/\\\/laplandrestaurant.fi\\\/userassets\\\/uploads\\\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\",\"name\":\"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/#website\"},\"datePublished\":\"2023-09-07T10:31:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/userassets\\\/uploads\\\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laplandrestaurant.fi\\\/userassets\\\/uploads\\\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/userassets\\\/uploads\\\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/#website\",\"url\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/\",\"name\":\"Lapland Restaurant Kotahovi\",\"description\":\"Unique and Atmospheric Restaurant in Lapland Finland at the Acrtic Circle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/search\\\/{search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","og_locale":"fi_FI","og_type":"article","og_title":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi","og_url":"\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","og_site_name":"Lapland Restaurant Kotahovi","og_image":[{"width":550,"height":314,"url":"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","url":"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","name":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314 - Lapland Restaurant Kotahovi","isPartOf":{"@id":"https:\/\/laplandrestaurant.fi\/fi\/#website"},"datePublished":"2023-09-07T10:31:47+00:00","breadcrumb":{"@id":"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laplandrestaurant.fi\/userassets\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laplandrestaurant.fi\/fi\/"},{"@type":"ListItem","position":2,"name":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314"}]},{"@type":"WebSite","@id":"https:\/\/laplandrestaurant.fi\/fi\/#website","url":"https:\/\/laplandrestaurant.fi\/fi\/","name":"Lapland Restaurant Kotahovi","description":"Unique and Atmospheric Restaurant in Lapland Finland at the Acrtic Circle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laplandrestaurant.fi\/fi\/search\/{search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"314\" src=\"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg\" class=\"attachment-medium size-medium img-fluid\" alt=\"\" srcset=\"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg 550w, https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-260x148.jpg 260w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":550,"height":314,"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","filesize":53881,"sizes":{"thumbnail":{"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-150x150.jpg","width":150,"height":150,"filesize":16029,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-150x150.jpg"},"slide_small":{"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-350x165.jpg","width":350,"height":165,"filesize":25174,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-350x165.jpg"},"gallery":{"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-260x148.jpg","width":260,"height":148,"filesize":20224,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-260x148.jpg"},"nosto":{"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-253x253.jpg","width":253,"height":253,"filesize":26759,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4-253x253.jpg"},"full":{"file":"electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","width":550,"height":314,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg"}},"image_meta":{"aperture":"5.6","credit":"Kaisa_Siren","camera":"Canon EOS-1D X Mark II","caption":"Aurora eMotion offers electric snowmobile safaris in Lapland","created_timestamp":"1547038133","copyright":"","focal_length":"200","iso":"2500","shutter_speed":"0.003125","title":"Aurora eMotion offers electric snowmobile safaris in Lapland","orientation":"0","keywords":[]}},"post":null,"source_url":"\/wp-content\/uploads\/electric-snowmobile-safaris-rovaniemi-scaled-aspect-ratio-550-314-4.jpg","_links":{"self":[{"href":"https:\/\/laplandrestaurant.fi\/fi\/wp-json\/wp\/v2\/media\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laplandrestaurant.fi\/fi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/laplandrestaurant.fi\/fi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/laplandrestaurant.fi\/fi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/laplandrestaurant.fi\/fi\/wp-json\/wp\/v2\/comments?post=3169"}]}}