{"id":3856,"date":"2026-07-06T09:06:52","date_gmt":"2026-07-06T06:06:52","guid":{"rendered":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png"},"modified":"2026-07-06T09:06:52","modified_gmt":"2026-07-06T06:06:52","slug":"visit-rovaniemi-partner-logo-png-2025-2","status":"inherit","type":"attachment","link":"https:\/\/laplandrestaurant.fi\/de\/etusivu\/visit-rovaniemi-partner-logo-png-2025-2\/","title":{"rendered":"Visit-Rovaniemi-Partner-logo-PNG-2025"},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3856","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi\" \/>\n<meta property=\"og:url\" content=\"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\" \/>\n<meta property=\"og:site_name\" content=\"Lapland Restaurant Kotahovi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\\\/wp-content\\\/uploads\\\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\",\"url\":\"https:\\\/\\\/laplandrestaurant.fi\\\/wp-content\\\/uploads\\\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\",\"name\":\"Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/#website\"},\"datePublished\":\"2026-07-06T06:06:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/wp-content\\\/uploads\\\/Visit-Rovaniemi-Partner-logo-PNG-2025.png#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laplandrestaurant.fi\\\/wp-content\\\/uploads\\\/Visit-Rovaniemi-Partner-logo-PNG-2025.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/wp-content\\\/uploads\\\/Visit-Rovaniemi-Partner-logo-PNG-2025.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laplandrestaurant.fi\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laplandrestaurant.fi\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visit-Rovaniemi-Partner-logo-PNG-2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/#website\",\"url\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/\",\"name\":\"Lapland Restaurant Kotahovi\",\"description\":\"Unique and Atmospheric Restaurant in Lapland Finland at the Acrtic Circle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laplandrestaurant.fi\\\/fi\\\/search\\\/{search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","og_locale":"de_DE","og_type":"article","og_title":"Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi","og_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","og_site_name":"Lapland Restaurant Kotahovi","og_image":[{"width":600,"height":769,"url":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","url":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","name":"Visit-Rovaniemi-Partner-logo-PNG-2025 - Lapland Restaurant Kotahovi","isPartOf":{"@id":"https:\/\/laplandrestaurant.fi\/fi\/#website"},"datePublished":"2026-07-06T06:06:52+00:00","breadcrumb":{"@id":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laplandrestaurant.fi\/de\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/laplandrestaurant.fi\/de\/"},{"@type":"ListItem","position":3,"name":"Visit-Rovaniemi-Partner-logo-PNG-2025"}]},{"@type":"WebSite","@id":"https:\/\/laplandrestaurant.fi\/fi\/#website","url":"https:\/\/laplandrestaurant.fi\/fi\/","name":"Lapland Restaurant Kotahovi","description":"Unique and Atmospheric Restaurant in Lapland Finland at the Acrtic Circle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laplandrestaurant.fi\/fi\/search\/{search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png'><img loading=\"lazy\" decoding=\"async\" width=\"468\" height=\"600\" src=\"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-468x600.png\" class=\"attachment-medium size-medium img-fluid\" alt=\"\" srcset=\"https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-468x600.png 468w, https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-260x333.png 260w, https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-546x700.png 546w, https:\/\/laplandrestaurant.fi\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png 600w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":769,"file":"Visit-Rovaniemi-Partner-logo-PNG-2025.png","filesize":60420,"sizes":{"medium":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-468x600.png","width":468,"height":600,"filesize":24520,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-468x600.png"},"thumbnail":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-150x150.png","width":150,"height":150,"filesize":5408,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-150x150.png"},"slide":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-600x530.png","width":600,"height":530,"filesize":22515,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-600x530.png"},"slide_small":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-350x165.png","width":350,"height":165,"filesize":5364,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-350x165.png"},"gallery":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-260x333.png","width":260,"height":333,"filesize":11189,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-260x333.png"},"gallery_full":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-546x700.png","width":546,"height":700,"filesize":29408,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-546x700.png"},"nosto":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025-253x253.png","width":253,"height":253,"filesize":9645,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025-253x253.png"},"full":{"file":"Visit-Rovaniemi-Partner-logo-PNG-2025.png","width":600,"height":769,"mime_type":"image\/png","source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":521,"source_url":"\/wp-content\/uploads\/Visit-Rovaniemi-Partner-logo-PNG-2025.png","_links":{"self":[{"href":"https:\/\/laplandrestaurant.fi\/de\/wp-json\/wp\/v2\/media\/3856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laplandrestaurant.fi\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/laplandrestaurant.fi\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/laplandrestaurant.fi\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laplandrestaurant.fi\/de\/wp-json\/wp\/v2\/comments?post=3856"}]}}